{"id":2183,"date":"2025-05-28T18:40:27","date_gmt":"2025-05-28T18:40:27","guid":{"rendered":"https:\/\/www.balkantravelguide.com\/?post_type=destinations&#038;p=2183"},"modified":"2026-06-22T18:17:17","modified_gmt":"2026-06-22T18:17:17","slug":"canyons-du-montenegro","status":"publish","type":"destinations","link":"https:\/\/www.balkantravelguide.com\/fr\/destinations\/%d0%ba%d0%b0%d0%bd%d1%8c%d0%be%d0%bd%d1%8b-%d1%87%d0%b5%d1%80%d0%bd%d0%be%d0%b3%d0%be%d1%80%d0%b8%d0%b8\/","title":{"rendered":"Canyons"},"content":{"rendered":"<p data-start=\"1656\" data-end=\"2465\">Nous partons de Budva \u00e0 7h00 du matin. Le trajet passe par Cetinje et Podgorica en direction du canyon de la rivi\u00e8re Mora\u010da, o\u00f9 se trouve le monast\u00e8re Mora\u010da du XIIIe si\u00e8cle. Nous faisons une pause de 30 minutes au monast\u00e8re, puis nous poursuivons par Kola\u0161in et Mojkovac. La pause d\u00e9jeuner dure 1 heure dans un cadre verdoyant et magnifique au bord de la rivi\u00e8re Tara. Ensuite, nous nous dirigeons vers le pont \u0110ur\u0111evi\u0107a Tara \u2014 l\u2019un des lieux les plus visit\u00e9s du Mont\u00e9n\u00e9gro \u2014 o\u00f9 nous faisons une courte pause. L\u00e0, vous pouvez essayer la tyrolienne au-dessus du canyon. Nous continuons ensuite vers la c\u00e9l\u00e8bre montagne Durmitor. Le Durmitor est l\u2019un des cinq parcs nationaux du Mont\u00e9n\u00e9gro. Il comprend 18 lacs, dont le plus grand est le lac Noir, o\u00f9 nous nous arr\u00eatons pendant 1h30. Apr\u00e8s cela, nous poursuivons \u00e0 travers le canyon de la rivi\u00e8re Komarnica et Nik\u0161i\u0107 pour revenir \u00e0 Budva vers 20h30.<\/p>\n<p data-start=\"2467\" data-end=\"2769\" class=\"translation-block\"><strong data-start=\"2467\" data-end=\"2500\">Le tour n\u2019inclut pas :<\/strong> entr\u00e9e au monast\u00e8re 3\u202f\u20ac, entr\u00e9e au parc national 5\u202f\u20ac, taxe de \u017dabljak 1\u202f\u20ac, nourriture et boissons.<br data-start=\"2583\" data-end=\"2586\"><strong data-start=\"2586\" data-end=\"2596\">Conseil :<\/strong> couvrez vos \u00e9paules et genoux lors de la visite du monast\u00e8re, apportez un pull ou une veste car il peut faire frais en montagne. Prenez un maillot si vous pr\u00e9voyez de vous baigner dans le lac.<\/p>","protected":false},"featured_media":2184,"template":"","country":[10],"tour-category":[6,7],"class_list":["post-2183","destinations","type-destinations","status-publish","has-post-thumbnail","hentry","country-montenegro","tour-category-group-tour","tour-category-individual-tour"],"_links":{"self":[{"href":"https:\/\/www.balkantravelguide.com\/fr\/wp-json\/wp\/v2\/destinations\/2183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.balkantravelguide.com\/fr\/wp-json\/wp\/v2\/destinations"}],"about":[{"href":"https:\/\/www.balkantravelguide.com\/fr\/wp-json\/wp\/v2\/types\/destinations"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.balkantravelguide.com\/fr\/wp-json\/wp\/v2\/media\/2184"}],"wp:attachment":[{"href":"https:\/\/www.balkantravelguide.com\/fr\/wp-json\/wp\/v2\/media?parent=2183"}],"wp:term":[{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.balkantravelguide.com\/fr\/wp-json\/wp\/v2\/country?post=2183"},{"taxonomy":"tour-category","embeddable":true,"href":"https:\/\/www.balkantravelguide.com\/fr\/wp-json\/wp\/v2\/tour-category?post=2183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}